{"id":988625,"date":"2025-02-12T21:56:08","date_gmt":"2025-02-12T21:56:08","guid":{"rendered":"https:\/\/ejavisa.com\/?p=988625"},"modified":"2025-02-13T07:23:49","modified_gmt":"2025-02-13T07:23:49","slug":"richtlinien-des-innenministeriums-zur-staatsangehorigkeit","status":"publish","type":"post","link":"https:\/\/ejavisa.com\/de\/udhezimet-e-home-office-mbi-nenshtetesine\/","title":{"rendered":"Richtlinien des Innenministeriums zur Staatsb\u00fcrgerschaft."},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">&nbsp;<\/p>\n<p>Wer ab dem 10. Februar 2025 die Staatsb\u00fcrgerschaft beantragt und zuvor ohne die erforderliche Einreisegenehmigung oder elektronische Reisegenehmigung \u00fcber gef\u00e4hrliche Routen eingereist ist, dessen Antrag auf Staatsb\u00fcrgerschaft wird in der Regel abgelehnt.<\/p>\n<p>In den Leitlinien des Innenministeriums zur Staatsb\u00fcrgerschaft hei\u00dft es, dass der Abschnitt \u00fcber das \u201cAnforderungsmerkmal der Unbescholtenheit\u201c am Montag aktualisiert wurde, um klarzustellen, dass Antr\u00e4ge auf Staatsb\u00fcrgerschaft, bei denen eine illegale Einreise vorliegt, in der Regel abgelehnt werden, unabh\u00e4ngig davon, wann die illegale Einreise stattfand.<\/p>\n<p>In den Leitlinien hei\u00dft es: \u201cJedem Antragsteller, der ab dem 10. Februar 2025 die Staatsb\u00fcrgerschaft beantragt und zuvor illegal nach Gro\u00dfbritannien eingereist ist, wird der Antrag in der Regel abgelehnt, unabh\u00e4ngig davon, wie viel Zeit seit der illegalen Einreise vergangen ist.\u201c.<\/p>\n<p>Da diese Richtlinie auch auf Widerstand gesto\u00dfen ist, wird erwartet, dass im Parlament dar\u00fcber debattiert wird, ob sie angenommen wird oder nicht.<\/p><\/div>\n<p><!-- .vgblk-rw-wrapper --><\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Bei Personen, die ab dem 10. Februar 2025 die Staatsb\u00fcrgerschaft beantragen und zuvor ohne die erforderliche Einreisegenehmigung oder elektronische Reisegenehmigung auf gef\u00e4hrliche Weise eingereist sind, wird der Antrag auf Staatsb\u00fcrgerschaft in der Regel abgelehnt. In den Leitlinien des Innenministeriums zur Staatsb\u00fcrgerschaft wird pr\u00e4zisiert, dass der Punkt, der sich auf \u201cdie Anforderung der charakterlichen Eignung\u201c bezieht\u2026<\/p>","protected":false},"author":1,"featured_media":988626,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-988625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eja-visa"],"_links":{"self":[{"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/posts\/988625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/comments?post=988625"}],"version-history":[{"count":3,"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/posts\/988625\/revisions"}],"predecessor-version":[{"id":988629,"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/posts\/988625\/revisions\/988629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/media\/988626"}],"wp:attachment":[{"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/media?parent=988625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/categories?post=988625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ejavisa.com\/de\/wp-json\/wp\/v2\/tags?post=988625"}],"curies":[{"name":"WordPress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}