{"id":988271,"date":"2023-04-02T21:20:27","date_gmt":"2023-04-02T21:20:27","guid":{"rendered":"https:\/\/ejavisa.com\/en\/?page_id=988271"},"modified":"2023-04-05T21:58:56","modified_gmt":"2023-04-05T21:58:56","slug":"faire-une-demande-de-visa-de-conjoint-au-royaume-uni","status":"publish","type":"page","link":"https:\/\/ejavisa.com\/fr\/viza-britanike\/apliko-per-vize-bashkeshortore-ne-mbreterine-e-bashkuar\/","title":{"rendered":"Visa de regroupement familial"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\n<h2>\n\tVisa de regroupement familial au Royaume-Uni\n\t<\/h2>\n\t<p>Les ressortissants britanniques ou les personnes titulaires d'un permis de s\u00e9jour permanent au Royaume-Uni peuvent demander \u00e0 faire venir leur partenaire ou leur conjoint au Royaume-Uni. Les visas de partenaire sont accessibles aux personnes mari\u00e9es (ou en couple) avec un citoyen britannique, un citoyen de l'UE ou m\u00eame un ressortissant d'un pays hors UE.<\/p>\n\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?phone=355697035626\" target=\"_self\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\tContactez-nous\n\t\t\t\t\t<\/a>\n\t<p>K\u00ebto viza referohen zyrtarisht si viz\u00eb &#8220;bashkim familjar me nj\u00eb person me leje q\u00ebndrimi t\u00eb p\u00ebrhershme n\u00eb MB&#8221; dhe kjo e b\u00ebn relativisht t\u00eb leht\u00eb q\u00eb\u00a0 partner\u00ebt ose bashk\u00ebshort\u00ebt e qytetar\u00ebve britanik\u00eb t&#8217;ju bashkohen atyre n\u00eb MB.<\/p>\n<p><b>Qui peut demander un visa de conjoint au Royaume-Uni ?<\/b><\/p>\n<p>Vous pouvez demander ce visa si vous \u00eates mari\u00e9(e) \u00e0 un(e) citoyen(ne) britannique ou \u00e0 une personne qui a le droit de vivre et de travailler au Royaume-Uni, ou qui b\u00e9n\u00e9ficie du statut de r\u00e9sident permanent au Royaume-Uni (c'est-\u00e0-dire une personne titulaire d'un visa valide ou d'un permis de s\u00e9jour illimit\u00e9 (ILR)).<\/p>\n<p><b>Travailler au Royaume-Uni sans aucune restriction.<\/b><\/p>\n<p>Le visa de regroupement familial vous permet de vivre et de travailler au Royaume-Uni pendant une p\u00e9riode initiale de deux ans et demi, et vous pouvez \u00e9galement quitter le pays et y revenir \u00e0 plusieurs reprises. Au bout de deux ans et demi, vous pouvez demander \u00e0 prolonger votre s\u00e9jour au Royaume-Uni pour une nouvelle p\u00e9riode de deux ans et demi.\u00a0<\/p>\n<p>Une fois que vous aurez r\u00e9sid\u00e9 au Royaume-Uni pendant cinq ans au total, vous pourrez peut-\u00eatre demander le statut de r\u00e9sident permanent.\u00a0<\/p>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"2560\" src=\"https:\/\/ejavisa.com\/en\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-scaled.jpg\" alt=\"portrait d&#039;une jeune femme prenant des photos pendant ses vacances\" itemprop=\"image\" title=\"portrait d&#039;une jeune femme prenant des photos pendant ses vacances\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-scaled.jpg 2560w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-300x300.jpg 300w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-1024x1024.jpg 1024w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-150x150.jpg 150w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-768x768.jpg 768w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-1536x1536.jpg 1536w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-2048x2048.jpg 2048w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-1260x1260.jpg 1260w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-630x630.jpg 630w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-420x420.jpg 420w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-840x840.jpg 840w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/portrait-young-woman-taking-pictures-holiday-min-315x315.jpg 315w\" \/>\t\t\t\t\t\t\t\n<h4>\n\t\t\t<a href=\"https:\/\/ejavisa.com\/fr\/visa-britannique\/visa-de-visiteur-standard\/\" title=\"Visa touristique pour le Royaume-Uni\" target=\"_self\" rel=\"noopener\">\n\tVisa touristique pour le Royaume-Uni\n\t\t\t<\/a>\n\t<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"2560\" src=\"https:\/\/ejavisa.com\/en\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-scaled.jpg\" alt=\"un jeune employ\u00e9 assis \u00e0 son bureau\" itemprop=\"image\" title=\"un jeune employ\u00e9 assis \u00e0 son bureau\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-scaled.jpg 2560w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-300x300.jpg 300w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-1024x1024.jpg 1024w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-150x150.jpg 150w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-768x768.jpg 768w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-1536x1536.jpg 1536w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-2048x2048.jpg 2048w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-1260x1260.jpg 1260w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-630x630.jpg 630w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-420x420.jpg 420w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-840x840.jpg 840w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/young-employee-sitting-office-desk-min-315x315.jpg 315w\" \/>\t\t\t\t\t\t\t\n<h4>\n\t\t\t<a href=\"https:\/\/ejavisa.com\/fr\/visa-britannique\/visa-de-travail-au-royaume-uni\/\" title=\"Visa de travail au Royaume-Uni\" target=\"_self\" rel=\"noopener\">\n\tVisa de travail au Royaume-Uni\n\t\t\t<\/a>\n\t<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"2560\" src=\"https:\/\/ejavisa.com\/en\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-scaled.jpg\" alt=\"Concept de retour \u00e0 l&#039;\u00e9cole avec une femme \u00e9tudiant \u00e0 la biblioth\u00e8que (1)\" itemprop=\"image\" title=\"Concept de retour \u00e0 l&#039;\u00e9cole avec une femme \u00e9tudiant \u00e0 la biblioth\u00e8que (1)\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-scaled.jpg 2560w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-300x300.jpg 300w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-1024x1024.jpg 1024w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-150x150.jpg 150w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-768x768.jpg 768w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-1536x1536.jpg 1536w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-2048x2048.jpg 2048w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-1260x1260.jpg 1260w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-630x630.jpg 630w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-420x420.jpg 420w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-840x840.jpg 840w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/back-school-concept-with-woman-studying-library-min-1-315x315.jpg 315w\" \/>\t\t\t\t\t\t\t\n<h4>\n\t\t\t<a href=\"https:\/\/ejavisa.com\/fr\/visa-britannique\/studio-au-royaume-uni\/\" title=\"Visa d&#039;\u00e9tudes pour le Royaume-Uni\" target=\"_self\" rel=\"noopener\">\n\tVisa d'\u00e9tudes pour le Royaume-Uni\n\t\t\t<\/a>\n\t<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/ejavisa.com\/en\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-300x300.jpg\" alt=\"parents-avec-leur-fille-allong\u00e9e-parmi-les-feuilles-d&#039;automne-dans-un-petit-parc\" itemprop=\"image\" title=\"parents-avec-leur-fille-allong\u00e9e-parmi-les-feuilles-d&#039;automne-dans-un-petit-parc\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-300x300.jpg 300w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-1024x1024.jpg 1024w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-150x150.jpg 150w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-768x768.jpg 768w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-1536x1536.jpg 1536w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-2048x2048.jpg 2048w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-1260x1260.jpg 1260w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-630x630.jpg 630w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-420x420.jpg 420w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-840x840.jpg 840w, https:\/\/ejavisa.com\/wp-content\/uploads\/2023\/04\/parents-with-daughter-lying-autumn-leaves-park-min-315x315.jpg 315w\" \/>\t\t\t\t\t\t\t\n<h4>\n\t\t\t<a href=\"https:\/\/ejavisa.com\/fr\/visa-britannique\/faire-une-demande-de-visa-de-conjoint-au-royaume-uni\/\" title=\"Visa familial au Royaume-Uni\" target=\"_self\" rel=\"noopener\">\n\tVisa familial au Royaume-Uni\n\t\t\t<\/a>\n\t<\/h4>\n\t<section id=\"Content_C016_Col00\" data-sf-element=\"content-narrow\" data-placeholder-label=\"Content Narrow\">\n<section id=\"Content_C016_Col00\" data-sf-element=\"content-narrow\" data-placeholder-label=\"Content Narrow\">\n<p>Vous pouvez \u00e9galement demander un visa de conjoint ou de partenaire dans l'une des situations suivantes :<\/p>\n<ul>\n<li aria-level=\"1\">Si vous \u00eates mari\u00e9(e) ou en couple depuis longtemps avec une personne r\u00e9sidant au Royaume-Uni \u00e0 qui un visa \u00e9tudiant a \u00e9t\u00e9 accord\u00e9.\u00a0<\/li>\n<li aria-level=\"1\">Si vous \u00eates mari\u00e9(e) ou en couple depuis longtemps avec une personne titulaire d'un visa de travailleur qualifi\u00e9 au Royaume-Uni.<\/li>\n<li aria-level=\"1\">Si vous \u00eates mari\u00e9(e) ou en couple depuis longtemps avec une personne titulaire d'un visa d'affaires ou d'investisseur (et autoris\u00e9e \u00e0 rester au Royaume-Uni)<\/li>\n<\/ul>\n<p><b>Crit\u00e8res g\u00e9n\u00e9raux pour le visa de conjoint :<\/b><\/p>\n<ul>\n<li>\u00catre mari\u00e9 ou pouvoir prouver que vous avez v\u00e9cu avec une personne \u00e9ligible pendant deux ans.\u00a0<\/li>\n<li>R\u00e9pondre au crit\u00e8re de revenu minimum de 18 600 \u00a3 par an ou disposer d'une \u00e9pargne de 62 500 \u00a3.<\/li>\n<li>Si vous avez l'intention de vous marier dans les six prochains mois.<\/li>\n<\/ul>\n<\/section>\n<\/section>\n\n<\/div><!-- .vgblk-rw-wrapper -->","protected":false},"excerpt":{"rendered":"<p>Viz\u00eb bashkimi familjar n\u00eb MB N\u00ebnshtetasit Britanik ose ata t\u00eb pajisur me leje t\u00eb p\u00ebrhershme q\u00ebndrimi n\u00eb Mbret\u00ebrin\u00eb e Bashkuar kan\u00eb t\u00eb drejt\u00eb t\u00eb aplikojn\u00eb p\u00ebr t\u00eb sjell\u00eb partnerin ose bashk\u00ebshortin e tyre n\u00eb MB. Vizat e partnerit jan\u00eb t\u00eb disponueshme p\u00ebr ata t\u00eb martuar me (ose n\u00eb nj\u00eb marr\u00ebdh\u00ebnie me) nj\u00eb shtetas britanik, nj\u00eb&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":988342,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-988271","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/pages\/988271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/comments?post=988271"}],"version-history":[{"count":17,"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/pages\/988271\/revisions"}],"predecessor-version":[{"id":988498,"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/pages\/988271\/revisions\/988498"}],"up":[{"embeddable":true,"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/pages\/988342"}],"wp:attachment":[{"href":"https:\/\/ejavisa.com\/fr\/wp-json\/wp\/v2\/media?parent=988271"}],"curies":[{"name":"WordPress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}